{"id":51,"count":0,"description":"","link":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/metal-tray\/","name":"Metal Tray","slug":"metal-tray","taxonomy":"product_cat","parent":49,"meta":[],"menu_order":0,"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/metal-tray\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/51\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/shop-all\\\/#listItem\",\"name\":\"SHOP ALL\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/shop-all\\\/#listItem\",\"position\":2,\"name\":\"SHOP ALL\",\"item\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/shop-all\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/product-category\\\/tray\\\/#listItem\",\"name\":\"Tray\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/product-category\\\/tray\\\/#listItem\",\"position\":3,\"name\":\"Tray\",\"item\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/product-category\\\/tray\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/product-category\\\/tray\\\/metal-tray\\\/#listItem\",\"name\":\"Metal Tray\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/shop-all\\\/#listItem\",\"name\":\"SHOP ALL\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/product-category\\\/tray\\\/metal-tray\\\/#listItem\",\"position\":4,\"name\":\"Metal Tray\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/product-category\\\/tray\\\/#listItem\",\"name\":\"Tray\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/51\\\/#collectionpage\",\"url\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/51\\\/\",\"name\":\"Metal Tray - AK Handicrafts\",\"inLanguage\":\"ru-RU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/51\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/#organization\",\"name\":\"AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts\",\"description\":\"Transform Your Space with Timeless Handicrafts\",\"url\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/\",\"email\":\"akhandicraft0786@gmail.com\",\"telephone\":\"+919389469426\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"value\":10},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/akhandicrafts.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-09-at-11.14.34-PM-1.jpeg\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/51\\\/#organizationLogo\",\"width\":840,\"height\":840},\"image\":{\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/51\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/\",\"name\":\"AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts\",\"alternateName\":\"akhandicrafts\",\"description\":\"Transform Your Space with Timeless Handicrafts\",\"inLanguage\":\"ru-RU\",\"publisher\":{\"@id\":\"https:\\\/\\\/akhandicrafts.com\\\/ru\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Metal Tray - AK Handicrafts","description":"","canonical_url":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/metal-tray\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/51\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru#listItem","position":1,"name":"Home","item":"https:\/\/akhandicrafts.com\/ru","nextItem":{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/shop-all\/#listItem","name":"SHOP ALL"}},{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/shop-all\/#listItem","position":2,"name":"SHOP ALL","item":"https:\/\/akhandicrafts.com\/ru\/shop-all\/","nextItem":{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/#listItem","name":"Tray"},"previousItem":{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/#listItem","position":3,"name":"Tray","item":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/","nextItem":{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/metal-tray\/#listItem","name":"Metal Tray"},"previousItem":{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/shop-all\/#listItem","name":"SHOP ALL"}},{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/metal-tray\/#listItem","position":4,"name":"Metal Tray","previousItem":{"@type":"ListItem","@id":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/#listItem","name":"Tray"}}]},{"@type":"CollectionPage","@id":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/51\/#collectionpage","url":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/51\/","name":"Metal Tray - AK Handicrafts","inLanguage":"ru-RU","isPartOf":{"@id":"https:\/\/akhandicrafts.com\/ru\/#website"},"breadcrumb":{"@id":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/51\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/akhandicrafts.com\/ru\/#organization","name":"AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts","description":"Transform Your Space with Timeless Handicrafts","url":"https:\/\/akhandicrafts.com\/ru\/","email":"akhandicraft0786@gmail.com","telephone":"+919389469426","numberOfEmployees":{"@type":"QuantitativeValue","value":10},"logo":{"@type":"ImageObject","url":"https:\/\/akhandicrafts.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-09-at-11.14.34-PM-1.jpeg","@id":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/51\/#organizationLogo","width":840,"height":840},"image":{"@id":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/51\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/akhandicrafts.com\/ru\/#website","url":"https:\/\/akhandicrafts.com\/ru\/","name":"AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts AK Handicrafts","alternateName":"akhandicrafts","description":"Transform Your Space with Timeless Handicrafts","inLanguage":"ru-RU","publisher":{"@id":"https:\/\/akhandicrafts.com\/ru\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/akhandicrafts.com\/ru\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/akhandicrafts.com\/ru\/shop-all\/\" title=\"SHOP ALL\">SHOP ALL<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/\" title=\"Tray\">Tray<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMetal Tray\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/akhandicrafts.com\/ru"},{"label":"SHOP ALL","link":"https:\/\/akhandicrafts.com\/ru\/shop-all\/"},{"label":"Tray","link":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/"},{"label":"Metal Tray","link":"https:\/\/akhandicrafts.com\/ru\/product-category\/tray\/metal-tray\/"}],"_links":{"self":[{"href":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product_cat\/49"}],"wp:post_type":[{"href":"https:\/\/akhandicrafts.com\/ru\/wp-json\/wp\/v2\/product?product_cat=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}